{"id":570,"date":"2020-04-23T18:40:04","date_gmt":"2020-04-23T16:40:04","guid":{"rendered":"http:\/\/www.nautisea.com\/?p=570"},"modified":"2020-05-13T17:01:30","modified_gmt":"2020-05-13T15:01:30","slug":"astrea-42-balade-en-mer","status":"publish","type":"post","link":"https:\/\/www.nautisea.com\/index.php\/2020\/04\/23\/astrea-42-balade-en-mer\/","title":{"rendered":"Astrea 42 balade en mer"},"content":{"rendered":"<p>Petite balade en mer devant Marseille \u00e0 bord du premier Astrea 42 de chez Fountaine pajot.<\/p>\n<p><iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/eu3zm1mI84s?controls=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<p>==========================================<br \/>\nMerci pour le visionnage, vous aimez nos vid\u00e9os ? faites le savoir sur les r\u00e9seaux sociaux, un pouce en l\u2019air, un coeur, un commentaire\u2026 par avance merci \ud83d\ude42<\/p>\n<p>Pour rester inform\u00e9 de nos nouvelles publications, abonnez-vous \u00e0 notre cha\u00eene Youtube.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Petite balade en mer devant Marseille \u00e0 bord du premier Astrea 42 de chez Fountaine pajot. ========================================== Merci pour le visionnage, vous aimez nos vid\u00e9os ? faites le savoir sur les r\u00e9seaux sociaux, un pouce en l\u2019air, un coeur, un commentaire\u2026 par avance merci \ud83d\ude42 Pour rester inform\u00e9 de nos nouvelles publications, abonnez-vous \u00e0 notre &hellip; <a href=\"https:\/\/www.nautisea.com\/index.php\/2020\/04\/23\/astrea-42-balade-en-mer\/\" class=\"more-link\">Continuer la lecture<span class=\"screen-reader-text\"> de &laquo;&nbsp;Astrea 42 balade en mer&nbsp;&raquo;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[5],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Astrea 42 balade en mer - NautiSea<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.nautisea.com\/index.php\/2020\/04\/23\/astrea-42-balade-en-mer\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Astrea 42 balade en mer - NautiSea\" \/>\n<meta property=\"og:description\" content=\"Petite balade en mer devant Marseille \u00e0 bord du premier Astrea 42 de chez Fountaine pajot. ========================================== Merci pour le visionnage, vous aimez nos vid\u00e9os ? faites le savoir sur les r\u00e9seaux sociaux, un pouce en l\u2019air, un coeur, un commentaire\u2026 par avance merci \ud83d\ude42 Pour rester inform\u00e9 de nos nouvelles publications, abonnez-vous \u00e0 notre &hellip; Continuer la lecture de &laquo;&nbsp;Astrea 42 balade en mer&nbsp;&raquo;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.nautisea.com\/index.php\/2020\/04\/23\/astrea-42-balade-en-mer\/\" \/>\n<meta property=\"og:site_name\" content=\"NautiSea\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/nautiseaTV\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-23T16:40:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-05-13T15:01:30+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"nautisea\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.nautisea.com\/#website\",\"url\":\"https:\/\/www.nautisea.com\/\",\"name\":\"NautiSea\",\"description\":\"Mer &amp; Bateaux\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.nautisea.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.nautisea.com\/index.php\/2020\/04\/23\/astrea-42-balade-en-mer\/#webpage\",\"url\":\"https:\/\/www.nautisea.com\/index.php\/2020\/04\/23\/astrea-42-balade-en-mer\/\",\"name\":\"Astrea 42 balade en mer - NautiSea\",\"isPartOf\":{\"@id\":\"https:\/\/www.nautisea.com\/#website\"},\"datePublished\":\"2020-04-23T16:40:04+00:00\",\"dateModified\":\"2020-05-13T15:01:30+00:00\",\"author\":{\"@id\":\"https:\/\/www.nautisea.com\/#\/schema\/person\/3540198146884f52d309956c947f208f\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.nautisea.com\/index.php\/2020\/04\/23\/astrea-42-balade-en-mer\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.nautisea.com\/index.php\/2020\/04\/23\/astrea-42-balade-en-mer\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.nautisea.com\/index.php\/2020\/04\/23\/astrea-42-balade-en-mer\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.nautisea.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Astrea 42 balade en mer\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.nautisea.com\/#\/schema\/person\/3540198146884f52d309956c947f208f\",\"name\":\"nautisea\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.nautisea.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1eaa0bb2c59e435bc696fca6aceefbaf?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1eaa0bb2c59e435bc696fca6aceefbaf?s=96&d=mm&r=g\",\"caption\":\"nautisea\"},\"url\":\"https:\/\/www.nautisea.com\/index.php\/author\/nautisea\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Astrea 42 balade en mer - NautiSea","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.nautisea.com\/index.php\/2020\/04\/23\/astrea-42-balade-en-mer\/","og_locale":"fr_FR","og_type":"article","og_title":"Astrea 42 balade en mer - NautiSea","og_description":"Petite balade en mer devant Marseille \u00e0 bord du premier Astrea 42 de chez Fountaine pajot. ========================================== Merci pour le visionnage, vous aimez nos vid\u00e9os ? faites le savoir sur les r\u00e9seaux sociaux, un pouce en l\u2019air, un coeur, un commentaire\u2026 par avance merci \ud83d\ude42 Pour rester inform\u00e9 de nos nouvelles publications, abonnez-vous \u00e0 notre &hellip; Continuer la lecture de &laquo;&nbsp;Astrea 42 balade en mer&nbsp;&raquo;","og_url":"https:\/\/www.nautisea.com\/index.php\/2020\/04\/23\/astrea-42-balade-en-mer\/","og_site_name":"NautiSea","article_publisher":"https:\/\/www.facebook.com\/nautiseaTV","article_published_time":"2020-04-23T16:40:04+00:00","article_modified_time":"2020-05-13T15:01:30+00:00","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"nautisea"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.nautisea.com\/#website","url":"https:\/\/www.nautisea.com\/","name":"NautiSea","description":"Mer &amp; Bateaux","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.nautisea.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.nautisea.com\/index.php\/2020\/04\/23\/astrea-42-balade-en-mer\/#webpage","url":"https:\/\/www.nautisea.com\/index.php\/2020\/04\/23\/astrea-42-balade-en-mer\/","name":"Astrea 42 balade en mer - NautiSea","isPartOf":{"@id":"https:\/\/www.nautisea.com\/#website"},"datePublished":"2020-04-23T16:40:04+00:00","dateModified":"2020-05-13T15:01:30+00:00","author":{"@id":"https:\/\/www.nautisea.com\/#\/schema\/person\/3540198146884f52d309956c947f208f"},"breadcrumb":{"@id":"https:\/\/www.nautisea.com\/index.php\/2020\/04\/23\/astrea-42-balade-en-mer\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.nautisea.com\/index.php\/2020\/04\/23\/astrea-42-balade-en-mer\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.nautisea.com\/index.php\/2020\/04\/23\/astrea-42-balade-en-mer\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.nautisea.com\/"},{"@type":"ListItem","position":2,"name":"Astrea 42 balade en mer"}]},{"@type":"Person","@id":"https:\/\/www.nautisea.com\/#\/schema\/person\/3540198146884f52d309956c947f208f","name":"nautisea","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.nautisea.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/1eaa0bb2c59e435bc696fca6aceefbaf?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1eaa0bb2c59e435bc696fca6aceefbaf?s=96&d=mm&r=g","caption":"nautisea"},"url":"https:\/\/www.nautisea.com\/index.php\/author\/nautisea\/"}]}},"_links":{"self":[{"href":"https:\/\/www.nautisea.com\/index.php\/wp-json\/wp\/v2\/posts\/570"}],"collection":[{"href":"https:\/\/www.nautisea.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.nautisea.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.nautisea.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.nautisea.com\/index.php\/wp-json\/wp\/v2\/comments?post=570"}],"version-history":[{"count":2,"href":"https:\/\/www.nautisea.com\/index.php\/wp-json\/wp\/v2\/posts\/570\/revisions"}],"predecessor-version":[{"id":572,"href":"https:\/\/www.nautisea.com\/index.php\/wp-json\/wp\/v2\/posts\/570\/revisions\/572"}],"wp:attachment":[{"href":"https:\/\/www.nautisea.com\/index.php\/wp-json\/wp\/v2\/media?parent=570"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.nautisea.com\/index.php\/wp-json\/wp\/v2\/categories?post=570"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.nautisea.com\/index.php\/wp-json\/wp\/v2\/tags?post=570"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}